{"id":4388,"date":"2014-10-21T11:50:00","date_gmt":"2014-10-21T11:50:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/empresarios-de-sc-participam-da-feira-de-cantao\/"},"modified":"2014-10-21T11:50:00","modified_gmt":"2014-10-21T11:50:00","slug":"empresarios-de-sc-participam-da-feira-de-cantao","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/empresarios-de-sc-participam-da-feira-de-cantao\/","title":{"rendered":"Empres\u00e1rios de SC participam da Feira de Cant\u00e3o"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Integrantes da miss\u00e3o em visita \u00e0 montadora BAIC Beijing. Foto: Fiesc\/Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Fiiesc_China_Feira-de-Cant%C3%A3o-300x200.jpg\"><\/div>\n<p>Integrantes da miss\u00e3o em visita \u00e0 montadora BAIC Beijing. Foto: Fiesc\/Divulga\u00e7\u00e3o<\/p>\n<p>A visita \u00e0 ind\u00fastria automobil\u00edstica BAIC Beijing, que fatura US$ 30 bilh\u00f5es ao ano e pretende chegar a US$ 120 bilh\u00f5es\/ano at\u00e9 2020, chamou a aten\u00e7\u00e3o da miss\u00e3o de industriais brasileiros que visita a China. Uma comitiva de 66 empres\u00e1rios est\u00e3o no pa\u00eds asi\u00e1tico em miss\u00e3o liderada pela Fiesc (Federa\u00e7\u00e3o das Ind\u00fastrias de Santa Catarina). Eles participam da Feira de Cant\u00e3o, considerado o maior evento chin\u00eas de neg\u00f3cios, reunindo 60,2 mil expositores.<\/p>\n<p>\u201cS\u00e3o n\u00fameros que impressionam, ainda mais quando comparados com o que acontece no Brasil, onde temos uma economia praticamente parada\u201d, afirmou Tito Schmitt, vice-presidente regional da Federa\u00e7\u00e3o das Ind\u00fastrias de Santa Catarina (Fiesc) e l\u00edder da comitiva. Segundo Schmitt, a participa\u00e7\u00e3o na Feira de Cant\u00e3o superou as expectativas dos brasileiros, que descobriram tecnologias e oportunidades de neg\u00f3cios al\u00e9m das inicialmente previstas.<\/p>\n<p>Em parceria com China Trade Center, a Fiesc participou do pavilh\u00e3o internacional, servindo como ponto de encontro para a delega\u00e7\u00e3o brasileira e promovendo as ind\u00fastrias catarinenses. No stand, recebeu visitantes interessados em conhecer oportunidades no Brasil nos segmentos de alimentos e bebidas, madeira e pl\u00e1sticos. Tamb\u00e9m divulgou o programa Portos.SC, que promove os terminais catarinenses como ponto de conex\u00e3o log\u00edstica com o Brasil.Durante semin\u00e1rio em Guangzhou, no sul do pa\u00eds, o representante da Apex-Brasil, Cesar Yu, destacou que a China tem comprado mais couro brasileiro por conta do aumento da demanda do setor automotivo. O pa\u00eds tamb\u00e9m tem importado cal\u00e7ados, especialmente os infantis. Ele falou ainda do sucesso da marca Havaianas, que conta com 100 quiosques no pa\u00eds asi\u00e1tico.<\/p>\n<p>O c\u00f4nsul-geral do Brasil em Guangzhou, Jos\u00e9 Lessa, salientou que a China cresceu mais de 10% ao ano nos \u00faltimos anos. Ele lembrou que s\u00f3 a prov\u00edncia de Guangdong, onde a comitiva est\u00e1, registrou em 2013 PIB de US$ 1,2 trilh\u00e3o, metade do PIB brasileiro. Aos industriais ele lembrou que \u00e9 uma prov\u00edncia bastante promissora para fazer neg\u00f3cios.<\/p>\n<p>Ainda em Guangzhou o grupo realizou visita t\u00e9cnica \u00e0 Retop, empresa l\u00edder na fabrica\u00e7\u00e3o de telas e pain\u00e9is de LED na China, com atua\u00e7\u00e3o no mercado mundial. A comitiva foi recebida pelo vice-presidente da empresa, Jia Xiao Liang. A companhia, fundada em 1997, emprega 20 mil trabalhadores e possui o maior parque fabril de produ\u00e7\u00e3o de LED do pa\u00eds.De acordo com Schmitt, ap\u00f3s o retorno ao Brasil, previsto para amanh\u00e3, dia 22, os industriais devem levar de 60 a 90 dias para analisar os contatos e prospec\u00e7\u00f5es e encaminhar a realiza\u00e7\u00e3o de neg\u00f3cios com o pa\u00eds asi\u00e1tico.<\/p>\n<p>The post Empres\u00e1rios de SC participam da Feira de Cant\u00e3o appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/empresarios-de-sc-participam-da-feira-de-cantao\/\" class=\"colorbox\" title=\"Empres\u00e1rios de SC participam da Feira de Cant\u00e3o\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Integrantes da miss\u00e3o em visita \u00e0 montadora BAIC Beijing. Foto: Fiesc\/Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Fiiesc_China_Feira-de-Cant%C3%A3o-300x200.jpg\"><\/div>\n<p>Integrantes da miss\u00e3o em visita \u00e0 montadora BAIC Beijing. Foto: Fiesc\/Divulga\u00e7\u00e3o<\/p>\n<p>A visita \u00e0 ind\u00fastria automobil\u00edstica BAIC Beijing, que fatura US$ 30 bilh\u00f5es ao ano e pretende chegar a US$ 120 bilh\u00f5es\/ano at\u00e9 2020, chamou a aten\u00e7\u00e3o da miss\u00e3o de industriais brasileiros que visita a China. Uma comitiva de 66 empres\u00e1rios est\u00e3o no pa\u00eds asi\u00e1tico em miss\u00e3o liderada pela Fiesc (Federa\u00e7\u00e3o das Ind\u00fastrias de Santa Catarina). Eles participam da Feira de Cant\u00e3o, considerado o maior evento chin\u00eas de neg\u00f3cios, reunindo 60,2 mil expositores.<\/p>\n<p>\u201cS\u00e3o n\u00fameros que impressionam, ainda mais quando comparados com o que acontece no Brasil, onde temos uma economia praticamente parada\u201d, afirmou Tito Schmitt, vice-presidente regional da Federa\u00e7\u00e3o das Ind\u00fastrias de Santa Catarina (Fiesc) e l\u00edder da comitiva. Segundo Schmitt, a participa\u00e7\u00e3o na Feira de Cant\u00e3o superou as expectativas dos brasileiros, que descobriram tecnologias e oportunidades de neg\u00f3cios al\u00e9m das inicialmente previstas.<\/p>\n<p>Em parceria com China Trade Center, a Fiesc participou do pavilh\u00e3o internacional, servindo como ponto de encontro para a delega\u00e7\u00e3o brasileira e promovendo as ind\u00fastrias catarinenses. No stand, recebeu visitantes interessados em conhecer oportunidades no Brasil nos segmentos de alimentos e bebidas, madeira e pl\u00e1sticos. Tamb\u00e9m divulgou o programa Portos.SC, que promove os terminais catarinenses como ponto de conex\u00e3o log\u00edstica com o Brasil.Durante semin\u00e1rio em Guangzhou, no sul do pa\u00eds, o representante da Apex-Brasil, Cesar Yu, destacou que a China tem comprado mais couro brasileiro por conta do aumento da demanda do setor automotivo. O pa\u00eds tamb\u00e9m tem importado cal\u00e7ados, especialmente os infantis. Ele falou ainda do sucesso da marca Havaianas, que conta com 100 quiosques no pa\u00eds asi\u00e1tico.<\/p>\n<p>O c\u00f4nsul-geral do Brasil em Guangzhou, Jos\u00e9 Lessa, salientou que a China cresceu mais de 10% ao ano nos \u00faltimos anos. Ele lembrou que s\u00f3 a prov\u00edncia de Guangdong, onde a comitiva est\u00e1, registrou em 2013 PIB de US$ 1,2 trilh\u00e3o, metade do PIB brasileiro. Aos industriais ele lembrou que \u00e9 uma prov\u00edncia bastante promissora para fazer neg\u00f3cios.<\/p>\n<p>Ainda em Guangzhou o grupo realizou visita t\u00e9cnica \u00e0 Retop, empresa l\u00edder na fabrica\u00e7\u00e3o de telas e pain\u00e9is de LED na China, com atua\u00e7\u00e3o no mercado mundial. A comitiva foi recebida pelo vice-presidente da empresa, Jia Xiao Liang. A companhia, fundada em 1997, emprega 20 mil trabalhadores e possui o maior parque fabril de produ\u00e7\u00e3o de LED do pa\u00eds.De acordo com Schmitt, ap\u00f3s o retorno ao Brasil, previsto para amanh\u00e3, dia 22, os industriais devem levar de 60 a 90 dias para analisar os contatos e prospec\u00e7\u00f5es e encaminhar a realiza\u00e7\u00e3o de neg\u00f3cios com o pa\u00eds asi\u00e1tico.<\/p>\n<p>The post Empres\u00e1rios de SC participam da Feira de Cant\u00e3o appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4388","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4388"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4388\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}