{"id":4318,"date":"2014-10-16T12:10:00","date_gmt":"2014-10-16T12:10:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/mp-verifica-abuso-no-preco-de-itens-de-construcao\/"},"modified":"2014-10-16T12:10:00","modified_gmt":"2014-10-16T12:10:00","slug":"mp-verifica-abuso-no-preco-de-itens-de-construcao","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/mp-verifica-abuso-no-preco-de-itens-de-construcao\/","title":{"rendered":"MP verifica abuso no pre\u00e7o de itens de constru\u00e7\u00e3o"},"content":{"rendered":"<div align=\"left\">\n<div align=\"left\">\n<div align=\"left\"><span>O MPSC (Minist\u00e9rio P\u00fablico de Santa Catarina) expediu uma recomenda\u00e7\u00e3o aos comerciantes fornecedores de materiais de constru\u00e7\u00e3o do munic\u00edpio de Lages para n\u00e3o aumentar o pre\u00e7o dos produtos e servi\u00e7os. A recomenda\u00e7\u00e3o foi entregue, oficialmente, \u00e0 C\u00e2mara de Dirigentes Lojistas (CDL) de Lages. <\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>A recomenda\u00e7\u00e3o foi expedida em raz\u00e3o dos estragos causados pela forte chuva que atingiu a cidade nesta semana e da reclama\u00e7\u00e3o de alguns consumidores, que identificaram abuso nos pre\u00e7os. A Promotora de Justi\u00e7a Luciana Uller, da 1\u00aa Promotoria de Justi\u00e7a de Lages, publicou o of\u00edcio ap\u00f3s aumentos injustificados nos pre\u00e7os de materiais de constru\u00e7\u00e3o. A pr\u00e1tica atenta contra os princ\u00edpios do sistema de prote\u00e7\u00e3o ao consumidor estabelecidos no inciso V do artigo 170 e o \u00a7 4.\u00ba do artigo 173, ambos da Constitui\u00e7\u00e3o Federal.<\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>Caso o fornecimento dos materiais n\u00e3o seja feito da forma recomendada pelo MPSC e os atos abusivos persistam, os comerciantes poder\u00e3o receber san\u00e7\u00f5es administrativas, civis e penais correspondentes, que inclui pena de reclus\u00e3o que variam de dois a cinco anos ou ser aplicada multa de 20% do faturamento bruto da empresa.<\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>Os consumidores que se sentirem lesados dever\u00e3o dirigir-se at\u00e9 o Procon, localizado na Rua Martino Nerbass, n\u00ba 29, Centro de Lages, ou entrar em contato com a Promotoria de Justi\u00e7a por meio do e-mail<a class=\"colorbox\" href=\"mailto:lages01pj@mpsc.mp.br\" target=\"_blank\">l ages01pj@mpsc.mp.br<\/a> ou pelo telefone (49) 3221-2701.<\/span><\/div>\n<\/div>\n<\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<p>The post <a class=\"colorbox\" rel=\"nofollow\" href=\"http:\/\/economiasc.com.br\/mp-verifica-abuso-preco-de-itens-de-construcao\/\">MP verifica abuso no pre\u00e7o de itens de constru\u00e7\u00e3o<\/a> appeared first on <a class=\"colorbox\" rel=\"nofollow\" href=\"http:\/\/economiasc.com.br\/\">Economia SC<\/a>.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/mp-verifica-abuso-preco-de-itens-de-construcao\/\" class=\"colorbox\" title=\"MP verifica abuso no pre\u00e7o de itens de constru\u00e7\u00e3o\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div align=\"left\">\n<div align=\"left\">\n<div align=\"left\"><span>O MPSC (Minist\u00e9rio P\u00fablico de Santa Catarina) expediu uma recomenda\u00e7\u00e3o aos comerciantes fornecedores de materiais de constru\u00e7\u00e3o do munic\u00edpio de Lages para n\u00e3o aumentar o pre\u00e7o dos produtos e servi\u00e7os. A recomenda\u00e7\u00e3o foi entregue, oficialmente, \u00e0 C\u00e2mara de Dirigentes Lojistas (CDL) de Lages. <\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>A recomenda\u00e7\u00e3o foi expedida em raz\u00e3o dos estragos causados pela forte chuva que atingiu a cidade nesta semana e da reclama\u00e7\u00e3o de alguns consumidores, que identificaram abuso nos pre\u00e7os. A Promotora de Justi\u00e7a Luciana Uller, da 1\u00aa Promotoria de Justi\u00e7a de Lages, publicou o of\u00edcio ap\u00f3s aumentos injustificados nos pre\u00e7os de materiais de constru\u00e7\u00e3o. A pr\u00e1tica atenta contra os princ\u00edpios do sistema de prote\u00e7\u00e3o ao consumidor estabelecidos no inciso V do artigo 170 e o \u00a7 4.\u00ba do artigo 173, ambos da Constitui\u00e7\u00e3o Federal.<\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>Caso o fornecimento dos materiais n\u00e3o seja feito da forma recomendada pelo MPSC e os atos abusivos persistam, os comerciantes poder\u00e3o receber san\u00e7\u00f5es administrativas, civis e penais correspondentes, que inclui pena de reclus\u00e3o que variam de dois a cinco anos ou ser aplicada multa de 20% do faturamento bruto da empresa.<\/span><\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<div align=\"left\"><span>Os consumidores que se sentirem lesados dever\u00e3o dirigir-se at\u00e9 o Procon, localizado na Rua Martino Nerbass, n\u00ba 29, Centro de Lages, ou entrar em contato com a Promotoria de Justi\u00e7a por meio do e-mail<a class=\"colorbox\" href=\"mailto:lages01pj@mpsc.mp.br\" target=\"_blank\">l ages01pj@mpsc.mp.br<\/a> ou pelo telefone (49) 3221-2701.<\/span><\/div>\n<\/div>\n<\/div>\n<div align=\"left\"><span> <\/span><\/div>\n<p>The post <a class=\"colorbox\" rel=\"nofollow\" href=\"http:\/\/economiasc.com.br\/mp-verifica-abuso-preco-de-itens-de-construcao\/\">MP verifica abuso no pre\u00e7o de itens de constru\u00e7\u00e3o<\/a> appeared first on <a class=\"colorbox\" rel=\"nofollow\" href=\"http:\/\/economiasc.com.br\/\">Economia SC<\/a>.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4318","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4318"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4318\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}