{"id":4288,"date":"2014-10-14T17:48:00","date_gmt":"2014-10-14T17:48:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/lnfinity-blue-resort-tem-40-vagas-para-a-temporada\/"},"modified":"2014-10-14T17:48:00","modified_gmt":"2014-10-14T17:48:00","slug":"lnfinity-blue-resort-tem-40-vagas-para-a-temporada","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/lnfinity-blue-resort-tem-40-vagas-para-a-temporada\/","title":{"rendered":"lnfinity Blue Resort tem 40 vagas para a temporada"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Hotel de Balne\u00e1rio Cambori\u00fa abre mais de 40 vagas de emprego. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Hotel-Infinity-Blue-300x200.jpg\"><\/div>\n<p>Hotel de Balne\u00e1rio Cambori\u00fa abre mais de 40 vagas de emprego. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O lnfinity Blue Resort &amp; SPA, de Balne\u00e1rio Cambori\u00fa, est\u00e1 com mais de 40 vagas de trabalho abertas para contrata\u00e7\u00e3o imediata. S\u00e3o oportunidades efetivas e tempor\u00e1rias para os cargos de camareira, auxiliar de limpeza, gar\u00e7om, auxiliar de gar\u00e7om, manutencionista, mensageiro, auxiliar de cozinha, cozinheiro, massoterapeuta, porteiro, recepcionista, recreacionista e consultor de eventos.<\/p>\n<p>Os sal\u00e1rios iniciais variam entre R$ 1.268,00 e R$ 2.500,00 para uma jornada de 44 horas semanais. \u201cVale ressaltar que os tempor\u00e1rios que se destacarem t\u00eam chances de permanecerem conosco e garantirem um emprego efetivo\u201d, diz o gerente de Recursos Humano do resort, Dairon Grandi.<\/p>\n<p>O resort tamb\u00e9m conta com uma oportunidade para o cargo de governanta executiva. Para esta vaga, que tem remunera\u00e7\u00e3o compat\u00edvel com o mercado, s\u00e3o exigidas experi\u00eancias e forma\u00e7\u00e3o na \u00e1rea de hotelaria e turismo. \u201cO profissional ser\u00e1 respons\u00e1vel pela coordena\u00e7\u00e3o de equipes de camareiras, servi\u00e7os gerais, arruma\u00e7\u00e3o e limpeza dos apartamentos e \u00e1reas sociais do resort\u201d, explica o gerente de RH.<\/p>\n<p>Para todas as oportunidades, o trabalhador receber\u00e1 benef\u00edcios como alimenta\u00e7\u00e3o na empresa, seguro de vida, plano de sa\u00fade, vale transporte, pr\u00eamio assiduidade \u2013 ap\u00f3s experi\u00eancia -, e PLR (pr\u00eamio de participa\u00e7\u00e3o nos resultados). Os interessados podem enviar curr\u00edculo pelo e-mail rh@infinityblue.com.br ou pelo site do empreendimento (www.infinityblue.com.br), na se\u00e7\u00e3o Fale Conosco. Informa\u00e7\u00f5es pelo telefone (47) 3261-0330.<\/p>\n<p><strong>Sobre o Infinity Blue Resort &amp; SPA:<\/strong> Localizado a dez minutos do centro urbano de Balne\u00e1rio Cambori\u00fa, em Santa Catarina, o <strong>lnfinity Blue Resort &amp; SPA<\/strong> \u00e9 reconhecido por unir charme e sofistica\u00e7\u00e3o em meio \u00e0 natureza e \u00e0 beira mar. Com 122 apartamentos cuidadosamente constru\u00eddos em um complexo com 800 mil m\u00b2, o empreendimento oferece a h\u00f3spedes e visitantes uma s\u00e9rie de op\u00e7\u00f5es em entretenimento, gastronomia, lazer e bem-estar. \u00danico resort de Balne\u00e1rio Cambori\u00fa, o Infinity Blue possui quatro diferentes espa\u00e7os gastron\u00f4micos que trazem um mix de influ\u00eancias nacionais e internacionais para atender os mais diversos paladares. Com estrutura completa para receber variados formatos de eventos, o resort ainda conta com 13 espa\u00e7os que acomodam de 10 a 1.200 pessoas. Em seu SPA oferece diferentes tratamentos est\u00e9ticos e terap\u00eauticos e um completo sal\u00e3o de beleza. www.infinityblue.com.br<\/p>\n<p>The post lnfinity Blue Resort tem 40 vagas para a temporada appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/lnfinity-blue-resort-tem-40-vagas-para-temporada\/\" class=\"colorbox\" title=\"lnfinity Blue Resort tem 40 vagas para a temporada\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Hotel de Balne\u00e1rio Cambori\u00fa abre mais de 40 vagas de emprego. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Hotel-Infinity-Blue-300x200.jpg\"><\/div>\n<p>Hotel de Balne\u00e1rio Cambori\u00fa abre mais de 40 vagas de emprego. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O lnfinity Blue Resort &amp; SPA, de Balne\u00e1rio Cambori\u00fa, est\u00e1 com mais de 40 vagas de trabalho abertas para contrata\u00e7\u00e3o imediata. S\u00e3o oportunidades efetivas e tempor\u00e1rias para os cargos de camareira, auxiliar de limpeza, gar\u00e7om, auxiliar de gar\u00e7om, manutencionista, mensageiro, auxiliar de cozinha, cozinheiro, massoterapeuta, porteiro, recepcionista, recreacionista e consultor de eventos.<\/p>\n<p>Os sal\u00e1rios iniciais variam entre R$ 1.268,00 e R$ 2.500,00 para uma jornada de 44 horas semanais. \u201cVale ressaltar que os tempor\u00e1rios que se destacarem t\u00eam chances de permanecerem conosco e garantirem um emprego efetivo\u201d, diz o gerente de Recursos Humano do resort, Dairon Grandi.<\/p>\n<p>O resort tamb\u00e9m conta com uma oportunidade para o cargo de governanta executiva. Para esta vaga, que tem remunera\u00e7\u00e3o compat\u00edvel com o mercado, s\u00e3o exigidas experi\u00eancias e forma\u00e7\u00e3o na \u00e1rea de hotelaria e turismo. \u201cO profissional ser\u00e1 respons\u00e1vel pela coordena\u00e7\u00e3o de equipes de camareiras, servi\u00e7os gerais, arruma\u00e7\u00e3o e limpeza dos apartamentos e \u00e1reas sociais do resort\u201d, explica o gerente de RH.<\/p>\n<p>Para todas as oportunidades, o trabalhador receber\u00e1 benef\u00edcios como alimenta\u00e7\u00e3o na empresa, seguro de vida, plano de sa\u00fade, vale transporte, pr\u00eamio assiduidade \u2013 ap\u00f3s experi\u00eancia -, e PLR (pr\u00eamio de participa\u00e7\u00e3o nos resultados). Os interessados podem enviar curr\u00edculo pelo e-mail rh@infinityblue.com.br ou pelo site do empreendimento (www.infinityblue.com.br), na se\u00e7\u00e3o Fale Conosco. Informa\u00e7\u00f5es pelo telefone (47) 3261-0330.<\/p>\n<p><strong>Sobre o Infinity Blue Resort &amp; SPA:<\/strong> Localizado a dez minutos do centro urbano de Balne\u00e1rio Cambori\u00fa, em Santa Catarina, o <strong>lnfinity Blue Resort &amp; SPA<\/strong> \u00e9 reconhecido por unir charme e sofistica\u00e7\u00e3o em meio \u00e0 natureza e \u00e0 beira mar. Com 122 apartamentos cuidadosamente constru\u00eddos em um complexo com 800 mil m\u00b2, o empreendimento oferece a h\u00f3spedes e visitantes uma s\u00e9rie de op\u00e7\u00f5es em entretenimento, gastronomia, lazer e bem-estar. \u00danico resort de Balne\u00e1rio Cambori\u00fa, o Infinity Blue possui quatro diferentes espa\u00e7os gastron\u00f4micos que trazem um mix de influ\u00eancias nacionais e internacionais para atender os mais diversos paladares. Com estrutura completa para receber variados formatos de eventos, o resort ainda conta com 13 espa\u00e7os que acomodam de 10 a 1.200 pessoas. Em seu SPA oferece diferentes tratamentos est\u00e9ticos e terap\u00eauticos e um completo sal\u00e3o de beleza. www.infinityblue.com.br<\/p>\n<p>The post lnfinity Blue Resort tem 40 vagas para a temporada appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4288","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4288"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4288\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}