{"id":4274,"date":"2014-10-14T11:37:00","date_gmt":"2014-10-14T11:37:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/pecuaria-brasileira-busca-produtos-inovadores\/"},"modified":"2014-10-14T11:37:00","modified_gmt":"2014-10-14T11:37:00","slug":"pecuaria-brasileira-busca-produtos-inovadores","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/pecuaria-brasileira-busca-produtos-inovadores\/","title":{"rendered":"Pecu\u00e1ria brasileira busca produtos inovadores"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Nesta ter\u00e7a-feira, dia 14, \u00e9 comemorado o Dia Nacional da Pecu\u00e1ria. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/vacas.jpg\"><\/div>\n<p>Nesta ter\u00e7a-feira, dia 14, \u00e9 comemorado o Dia Nacional da Pecu\u00e1ria. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O Brasil possui uma das maiores \u00e1reas de produ\u00e7\u00e3o rural do mundo, ocupando cerca de 3,3 milh\u00f5es de quil\u00f4metros quadrados com agricultura e pecu\u00e1ria, segundo o \u00faltimo Censo Agropecu\u00e1rio do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Ocupando 38% do territ\u00f3rio nacional e movimentando 8% do Produto Interno Bruto (PIB), a agropecu\u00e1ria necessita constantemente de inova\u00e7\u00e3o em produtos veterin\u00e1rios, com solu\u00e7\u00f5es pr\u00e1ticas para o dia-a-dia.<\/p>\n<p>Pensando nisso, a Inovate comercializa produtos com tecnologias inovadoras e avan\u00e7adas que agregam ganhos produtivos e econ\u00f4micos para os pecuaristas, ao mesmo tempo em que cuidam do bem-estar animal. O \u00faltimo lan\u00e7amento da empresa  vem da Fran\u00e7a e \u00e9 in\u00e9dito no Brasil: o Secure Pig,  um ferom\u00f4nio sint\u00e9tico, subst\u00e2ncia qu\u00edmica similar a que \u00e9 produzida pelas gl\u00e2ndulas seb\u00e1ceas da porca ap\u00f3s o parto. Essa subst\u00e2ncia \u00e9 capaz de enviar uma mensagem sensorial que permite reduzir o estresse e adaptar melhor os leit\u00f5es ao manejo exigido pela suinocultura, como desmame, forma\u00e7\u00e3o de lotes e transporte, contribuindo para o aumento do bem-estar animal e da produtividade.<\/p>\n<p>O Nutri P \u00e9 uma pr\u00e9-mistura de aditivos aromatizantes,  composto por extratos vegetais \u00e0 base de polifen\u00f3is ricos em taninos hidrolis\u00e1veis, obtidos por um processo de extra\u00e7\u00e3o natural e adequado para a nutri\u00e7\u00e3o das aves e su\u00ednos O produto reduz a peristalse intestinal, desacelera a passagem de alimentos, permitindo melhor absor\u00e7\u00e3o de \u00e1gua e nutrientes; al\u00e9m disso, \u00e9 um potente antioxidante e antibacteriano natural que atua no controle de clostridioses e salmoneloses. Entre os principais benef\u00edcios destacam-se o controle da flora intestinal, melhora na consist\u00eancia das fezes, redu\u00e7\u00e3o do uso de antibi\u00f3ticos e a melhora da resposta imune.<\/p>\n<p>Al\u00e9m do Secure Pig e Nutri P, a empresa tamb\u00e9m comercializa o Orego Stim, produto obtido pela destila\u00e7\u00e3o do \u00f3leo da planta h\u00edbrida Origanum vulgare ssp. hirtum.  Ele substitui o uso de antibi\u00f3ticos, e funciona contra bact\u00e9rias Gram + e Gram -, sem provocar resist\u00eancia. Os dois componentes principais \u2013 Carvacrol e Timol \u2013 desorganizam a camada lip\u00eddica da parede celular quebrando as prote\u00ednas de liga\u00e7\u00e3o da parede celular, resultando em um desequil\u00edbrio de \u00e1gua e e consequente morte da c\u00e9lula. Dessa forma, \u00e9 imposs\u00edvel para a bact\u00e9ria desenvolver resist\u00eancia a essa a\u00e7\u00e3o, diferente dos antibi\u00f3ticos.<\/p>\n<p>Segundo o diretor da Inovate, Ari Caldeira de Almeida, a gama de produtos oferecidos pela empresa tem um objetivo claro. \u201cDesenvolvemos e comercializamos produtos veterin\u00e1rios inovadores que aumentam a produ\u00e7\u00e3o dos clientes e consequentemente trazem ganhos econ\u00f4micos, mas prezamos sempre pelo bem-estar animal, nossa preocupa\u00e7\u00e3o \u00e9 n\u00e3o deixar res\u00edduos nos animais, nem no ambiente\u201d, comenta Almeida.<\/p>\n<p>The post Pecu\u00e1ria brasileira busca produtos inovadores appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/pecuaria-brasileira-busca-produtos-inovadores\/\" class=\"colorbox\" title=\"Pecu\u00e1ria brasileira busca produtos inovadores\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Nesta ter\u00e7a-feira, dia 14, \u00e9 comemorado o Dia Nacional da Pecu\u00e1ria. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/vacas.jpg\"><\/div>\n<p>Nesta ter\u00e7a-feira, dia 14, \u00e9 comemorado o Dia Nacional da Pecu\u00e1ria. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O Brasil possui uma das maiores \u00e1reas de produ\u00e7\u00e3o rural do mundo, ocupando cerca de 3,3 milh\u00f5es de quil\u00f4metros quadrados com agricultura e pecu\u00e1ria, segundo o \u00faltimo Censo Agropecu\u00e1rio do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Ocupando 38% do territ\u00f3rio nacional e movimentando 8% do Produto Interno Bruto (PIB), a agropecu\u00e1ria necessita constantemente de inova\u00e7\u00e3o em produtos veterin\u00e1rios, com solu\u00e7\u00f5es pr\u00e1ticas para o dia-a-dia.<\/p>\n<p>Pensando nisso, a Inovate comercializa produtos com tecnologias inovadoras e avan\u00e7adas que agregam ganhos produtivos e econ\u00f4micos para os pecuaristas, ao mesmo tempo em que cuidam do bem-estar animal. O \u00faltimo lan\u00e7amento da empresa  vem da Fran\u00e7a e \u00e9 in\u00e9dito no Brasil: o Secure Pig,  um ferom\u00f4nio sint\u00e9tico, subst\u00e2ncia qu\u00edmica similar a que \u00e9 produzida pelas gl\u00e2ndulas seb\u00e1ceas da porca ap\u00f3s o parto. Essa subst\u00e2ncia \u00e9 capaz de enviar uma mensagem sensorial que permite reduzir o estresse e adaptar melhor os leit\u00f5es ao manejo exigido pela suinocultura, como desmame, forma\u00e7\u00e3o de lotes e transporte, contribuindo para o aumento do bem-estar animal e da produtividade.<\/p>\n<p>O Nutri P \u00e9 uma pr\u00e9-mistura de aditivos aromatizantes,  composto por extratos vegetais \u00e0 base de polifen\u00f3is ricos em taninos hidrolis\u00e1veis, obtidos por um processo de extra\u00e7\u00e3o natural e adequado para a nutri\u00e7\u00e3o das aves e su\u00ednos O produto reduz a peristalse intestinal, desacelera a passagem de alimentos, permitindo melhor absor\u00e7\u00e3o de \u00e1gua e nutrientes; al\u00e9m disso, \u00e9 um potente antioxidante e antibacteriano natural que atua no controle de clostridioses e salmoneloses. Entre os principais benef\u00edcios destacam-se o controle da flora intestinal, melhora na consist\u00eancia das fezes, redu\u00e7\u00e3o do uso de antibi\u00f3ticos e a melhora da resposta imune.<\/p>\n<p>Al\u00e9m do Secure Pig e Nutri P, a empresa tamb\u00e9m comercializa o Orego Stim, produto obtido pela destila\u00e7\u00e3o do \u00f3leo da planta h\u00edbrida Origanum vulgare ssp. hirtum.  Ele substitui o uso de antibi\u00f3ticos, e funciona contra bact\u00e9rias Gram + e Gram -, sem provocar resist\u00eancia. Os dois componentes principais \u2013 Carvacrol e Timol \u2013 desorganizam a camada lip\u00eddica da parede celular quebrando as prote\u00ednas de liga\u00e7\u00e3o da parede celular, resultando em um desequil\u00edbrio de \u00e1gua e e consequente morte da c\u00e9lula. Dessa forma, \u00e9 imposs\u00edvel para a bact\u00e9ria desenvolver resist\u00eancia a essa a\u00e7\u00e3o, diferente dos antibi\u00f3ticos.<\/p>\n<p>Segundo o diretor da Inovate, Ari Caldeira de Almeida, a gama de produtos oferecidos pela empresa tem um objetivo claro. \u201cDesenvolvemos e comercializamos produtos veterin\u00e1rios inovadores que aumentam a produ\u00e7\u00e3o dos clientes e consequentemente trazem ganhos econ\u00f4micos, mas prezamos sempre pelo bem-estar animal, nossa preocupa\u00e7\u00e3o \u00e9 n\u00e3o deixar res\u00edduos nos animais, nem no ambiente\u201d, comenta Almeida.<\/p>\n<p>The post Pecu\u00e1ria brasileira busca produtos inovadores appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4274","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4274"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4274\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}