{"id":4269,"date":"2014-10-13T15:30:00","date_gmt":"2014-10-13T15:30:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/eletrosul-capta-r-160-milhoes-para-investimentos\/"},"modified":"2014-10-13T15:30:00","modified_gmt":"2014-10-13T15:30:00","slug":"eletrosul-capta-r-160-milhoes-para-investimentos","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/eletrosul-capta-r-160-milhoes-para-investimentos\/","title":{"rendered":"Eletrosul capta R$ 160 milh\u00f5es para investimentos"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Os recursos ser\u00e3o aplicados nos segmentos e\u00f3lico, solar e de transmiss\u00e3o. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Eletrosul-300x200.jpg\"><\/div>\n<p>Recursos ser\u00e3o aplicados nos segmentos e\u00f3lico, solar e de transmiss\u00e3o. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O plano de investimentos da Eletrosul para as \u00e1reas de gera\u00e7\u00e3o e transmiss\u00e3o ter\u00e1 um suporte financeiro de aproximadamente R$ 160 milh\u00f5es, provenientes de financiamentos obtidos junto ao Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e Finep \u2013 Inova\u00e7\u00e3o e Pesquisa. Nessa soma, est\u00e1 considerado tamb\u00e9m o resultado da emiss\u00e3o de deb\u00eantures de infraestrutura da Transmissora Sul Brasileira de Energia (TSBE), Sociedade de Prop\u00f3sito Espec\u00edfico (SPE), na qual a Eletrosul tem 80% de participa\u00e7\u00e3o junto da Copel, que tem 20%. A contrata\u00e7\u00e3o dos financiamentos j\u00e1 foi aprovada e os recursos devem come\u00e7ar a ser repassados a partir deste m\u00eas.<\/p>\n<p>Um dos contratos de financiamento com o BNDES \u00e9 no valor de R$ 43,6 milh\u00f5es, que ser\u00e3o destinados \u00e0 amplia\u00e7\u00e3o do sistema de transmiss\u00e3o de Santa Catarina e Rio Grande do Sul. Muitas dessas obras \u2013 autorizadas por resolu\u00e7\u00f5es da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) \u2013 j\u00e1 est\u00e3o em andamento. Outros R$ 26,5 milh\u00f5es foram contratados junto ao BNDES para as obras da Interliga\u00e7\u00e3o El\u00e9trica Brasil-Uruguai, que est\u00e3o sendo realizadas em parceria com a Eletrobras. A holding ficou respons\u00e1vel pela constru\u00e7\u00e3o de uma subesta\u00e7\u00e3o em Candiota (RS) e a Eletrosul pelas linhas de transmiss\u00e3o (60 quil\u00f4metros em 525 kV e 3 km em 230 kV), que fazem a conex\u00e3o da nova subesta\u00e7\u00e3o com uma unidade existente e se estendem at\u00e9 a fronteira. Os financiamentos cobrem 55% do valor que est\u00e1 sendo investido pela Eletrosul.<\/p>\n<p>O financiamento da Finep, no valor de R$ 11,3 milh\u00f5es, ser\u00e1 aplicado em projetos de prospec\u00e7\u00e3o do potencial e\u00f3lico e solar com a implanta\u00e7\u00e3o de esta\u00e7\u00f5es de medi\u00e7\u00e3o de vento (anemom\u00e9tricas) e de radia\u00e7\u00e3o (solarim\u00e9tricas) nas \u00e1reas de atua\u00e7\u00e3o da Eletrosul. Parte dos estudos j\u00e1 est\u00e1 em andamento.<\/p>\n<p>E para buscar financiamento suplementar para suas obras, a TSBE \u2013 SPE controlada majoritariamente pela Eletrosul \u2013 realizou em setembro a segunda emiss\u00e3o de deb\u00eantures de infraestrutura. A opera\u00e7\u00e3o foi conduzida pelo Banco Votorantim e resultou na capta\u00e7\u00e3o de R$ 77,5 milh\u00f5es. As obras da TSBE, em fase final de implanta\u00e7\u00e3o, compreendem quase 800 km de linhas de transmiss\u00e3o de alta e extra-alta tens\u00e3o, entre o Paran\u00e1 e o Rio Grande do Sul, uma nova subesta\u00e7\u00e3o e amplia\u00e7\u00f5es em unidades existentes, que refor\u00e7am o interc\u00e2mbio de energia entre o Sudeste e o Sul. A SPE j\u00e1 havia obtido financiamento de R$ 267 milh\u00f5es junto ao BNDES.<\/p>\n<p>The post Eletrosul capta R$ 160 milh\u00f5es para investimentos appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/eletrosul-capta-r-160-milhoes-para-investimentos\/\" class=\"colorbox\" title=\"Eletrosul capta R$ 160 milh\u00f5es para investimentos\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Os recursos ser\u00e3o aplicados nos segmentos e\u00f3lico, solar e de transmiss\u00e3o. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/Eletrosul-300x200.jpg\"><\/div>\n<p>Recursos ser\u00e3o aplicados nos segmentos e\u00f3lico, solar e de transmiss\u00e3o. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O plano de investimentos da Eletrosul para as \u00e1reas de gera\u00e7\u00e3o e transmiss\u00e3o ter\u00e1 um suporte financeiro de aproximadamente R$ 160 milh\u00f5es, provenientes de financiamentos obtidos junto ao Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e Finep \u2013 Inova\u00e7\u00e3o e Pesquisa. Nessa soma, est\u00e1 considerado tamb\u00e9m o resultado da emiss\u00e3o de deb\u00eantures de infraestrutura da Transmissora Sul Brasileira de Energia (TSBE), Sociedade de Prop\u00f3sito Espec\u00edfico (SPE), na qual a Eletrosul tem 80% de participa\u00e7\u00e3o junto da Copel, que tem 20%. A contrata\u00e7\u00e3o dos financiamentos j\u00e1 foi aprovada e os recursos devem come\u00e7ar a ser repassados a partir deste m\u00eas.<\/p>\n<p>Um dos contratos de financiamento com o BNDES \u00e9 no valor de R$ 43,6 milh\u00f5es, que ser\u00e3o destinados \u00e0 amplia\u00e7\u00e3o do sistema de transmiss\u00e3o de Santa Catarina e Rio Grande do Sul. Muitas dessas obras \u2013 autorizadas por resolu\u00e7\u00f5es da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) \u2013 j\u00e1 est\u00e3o em andamento. Outros R$ 26,5 milh\u00f5es foram contratados junto ao BNDES para as obras da Interliga\u00e7\u00e3o El\u00e9trica Brasil-Uruguai, que est\u00e3o sendo realizadas em parceria com a Eletrobras. A holding ficou respons\u00e1vel pela constru\u00e7\u00e3o de uma subesta\u00e7\u00e3o em Candiota (RS) e a Eletrosul pelas linhas de transmiss\u00e3o (60 quil\u00f4metros em 525 kV e 3 km em 230 kV), que fazem a conex\u00e3o da nova subesta\u00e7\u00e3o com uma unidade existente e se estendem at\u00e9 a fronteira. Os financiamentos cobrem 55% do valor que est\u00e1 sendo investido pela Eletrosul.<\/p>\n<p>O financiamento da Finep, no valor de R$ 11,3 milh\u00f5es, ser\u00e1 aplicado em projetos de prospec\u00e7\u00e3o do potencial e\u00f3lico e solar com a implanta\u00e7\u00e3o de esta\u00e7\u00f5es de medi\u00e7\u00e3o de vento (anemom\u00e9tricas) e de radia\u00e7\u00e3o (solarim\u00e9tricas) nas \u00e1reas de atua\u00e7\u00e3o da Eletrosul. Parte dos estudos j\u00e1 est\u00e1 em andamento.<\/p>\n<p>E para buscar financiamento suplementar para suas obras, a TSBE \u2013 SPE controlada majoritariamente pela Eletrosul \u2013 realizou em setembro a segunda emiss\u00e3o de deb\u00eantures de infraestrutura. A opera\u00e7\u00e3o foi conduzida pelo Banco Votorantim e resultou na capta\u00e7\u00e3o de R$ 77,5 milh\u00f5es. As obras da TSBE, em fase final de implanta\u00e7\u00e3o, compreendem quase 800 km de linhas de transmiss\u00e3o de alta e extra-alta tens\u00e3o, entre o Paran\u00e1 e o Rio Grande do Sul, uma nova subesta\u00e7\u00e3o e amplia\u00e7\u00f5es em unidades existentes, que refor\u00e7am o interc\u00e2mbio de energia entre o Sudeste e o Sul. A SPE j\u00e1 havia obtido financiamento de R$ 267 milh\u00f5es junto ao BNDES.<\/p>\n<p>The post Eletrosul capta R$ 160 milh\u00f5es para investimentos appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4269","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4269"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4269\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}