{"id":4263,"date":"2014-10-13T13:19:00","date_gmt":"2014-10-13T13:19:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/frances-jean-tirole-ganha-premio-nobel-de-economia\/"},"modified":"2014-10-13T13:19:00","modified_gmt":"2014-10-13T13:19:00","slug":"frances-jean-tirole-ganha-premio-nobel-de-economia","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/frances-jean-tirole-ganha-premio-nobel-de-economia\/","title":{"rendered":"Franc\u00eas Jean Tirole ganha pr\u00eamio Nobel de Economia"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"O economista foi premiado por sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/coopera%C3%A7%C3%A3o1-300x220.jpg\"><\/div>\n<p>O economista foi premiado por sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O pr\u00eamio Nobel de Economia foi concedido ao economista franc\u00eas Jean Tirole em raz\u00e3o de sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado, segundo comunicado da Real Academia Sueca de Ci\u00eancias. \u201cMuitas ind\u00fastrias s\u00e3o dominadas por um pequeno n\u00famero de grandes empresas ou um \u00fanico monop\u00f3lio. Sem regula\u00e7\u00e3o, esses mercados produzem resultados socialmente indesejados \u2013 pre\u00e7os mais altos do que os que resultam dos custos ou empresas improdutivas que sobrevivem porque bloqueiam a entrada de outras, mais novas e mais produtivas\u201d, destacou o j\u00fari, ao se referir a Tirole como um dos economistas mais influentes da atualidade.<\/p>\n<p>O Nobel de Economia \u00e9 o \u00fanico que n\u00e3o estava inclu\u00eddo no testamento original do cientista e filantropo sueco, Alfredo Nobel. O pr\u00eamio criado em 1968, pelo Banco Central sueco, para celebrar o seu tricenten\u00e1rio. Foi entregue pela primeira vez em 1969, enquanto os outros pr\u00eamios s\u00e3o distribu\u00eddos desde 2001.<\/p>\n<p>A distin\u00e7\u00e3o de um franc\u00eas, este ano, marca uma ruptura com o dom\u00ednio americano na lista dos escolhidos.  Na \u00faltima d\u00e9cada, 18 dos 20 economistas que receberam o pr\u00eamio eram origin\u00e1rios dos Estados Unidos, incluindo um israelista-americano.<\/p>\n<p>Jean Tirole \u00e9 o terceiro franc\u00eas contemplado com o Nobel da Economia, depois de G\u00e9rard Debreu, em 1983, e Maurice Allais, em 1988. O economista trabalha na Universidade de Toulouse desde os anos 1990, depois de passar pelo Instituto de Economia de Massachussets, e era apontado como um dos favoritos ao Nobel h\u00e1 v\u00e1rios anos.<\/p>\n<p>Ele deve receber o pr\u00eamio e um cheque de 8 milh\u00f5es de coroas suecas, em 10 de dezembro, data que assinala o anivers\u00e1rio da morte do criador do Nobel, em Estocolmo. <strong>(Ag\u00eancia Brasil)<\/strong><\/p>\n<p>The post Franc\u00eas Jean Tirole ganha pr\u00eamio Nobel de Economia appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/frances-jean-tirole-ganha-premio-nobel-de-economia\/\" class=\"colorbox\" title=\"Franc\u00eas Jean Tirole ganha pr\u00eamio Nobel de Economia\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"O economista foi premiado por sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/coopera%C3%A7%C3%A3o1-300x220.jpg\"><\/div>\n<p>O economista foi premiado por sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>O pr\u00eamio Nobel de Economia foi concedido ao economista franc\u00eas Jean Tirole em raz\u00e3o de sua an\u00e1lise do poder e da regula\u00e7\u00e3o do mercado, segundo comunicado da Real Academia Sueca de Ci\u00eancias. \u201cMuitas ind\u00fastrias s\u00e3o dominadas por um pequeno n\u00famero de grandes empresas ou um \u00fanico monop\u00f3lio. Sem regula\u00e7\u00e3o, esses mercados produzem resultados socialmente indesejados \u2013 pre\u00e7os mais altos do que os que resultam dos custos ou empresas improdutivas que sobrevivem porque bloqueiam a entrada de outras, mais novas e mais produtivas\u201d, destacou o j\u00fari, ao se referir a Tirole como um dos economistas mais influentes da atualidade.<\/p>\n<p>O Nobel de Economia \u00e9 o \u00fanico que n\u00e3o estava inclu\u00eddo no testamento original do cientista e filantropo sueco, Alfredo Nobel. O pr\u00eamio criado em 1968, pelo Banco Central sueco, para celebrar o seu tricenten\u00e1rio. Foi entregue pela primeira vez em 1969, enquanto os outros pr\u00eamios s\u00e3o distribu\u00eddos desde 2001.<\/p>\n<p>A distin\u00e7\u00e3o de um franc\u00eas, este ano, marca uma ruptura com o dom\u00ednio americano na lista dos escolhidos.  Na \u00faltima d\u00e9cada, 18 dos 20 economistas que receberam o pr\u00eamio eram origin\u00e1rios dos Estados Unidos, incluindo um israelista-americano.<\/p>\n<p>Jean Tirole \u00e9 o terceiro franc\u00eas contemplado com o Nobel da Economia, depois de G\u00e9rard Debreu, em 1983, e Maurice Allais, em 1988. O economista trabalha na Universidade de Toulouse desde os anos 1990, depois de passar pelo Instituto de Economia de Massachussets, e era apontado como um dos favoritos ao Nobel h\u00e1 v\u00e1rios anos.<\/p>\n<p>Ele deve receber o pr\u00eamio e um cheque de 8 milh\u00f5es de coroas suecas, em 10 de dezembro, data que assinala o anivers\u00e1rio da morte do criador do Nobel, em Estocolmo. <strong>(Ag\u00eancia Brasil)<\/strong><\/p>\n<p>The post Franc\u00eas Jean Tirole ganha pr\u00eamio Nobel de Economia appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4263","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4263"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4263\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}