{"id":4261,"date":"2014-10-13T12:23:00","date_gmt":"2014-10-13T12:23:00","guid":{"rendered":"http:\/\/www.cdlbc.com.br\/portal\/noticias\/mercado-preve-que-pib-do-brasil-deve-crescer-028\/"},"modified":"2014-10-13T12:23:00","modified_gmt":"2014-10-13T12:23:00","slug":"mercado-preve-que-pib-do-brasil-deve-crescer-028","status":"publish","type":"post","link":"https:\/\/www.cdlbc.com.br\/portal\/noticias\/mercado-preve-que-pib-do-brasil-deve-crescer-028\/","title":{"rendered":"Mercado prev\u00ea que PIB do Brasil deve crescer 0,28%"},"content":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Essa \u00e9 a primeira alta na proje\u00e7\u00e3o do PIB feita pelo mercado financeiro depois de 19 quedas consecutivas. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/indice-subind-300x200.jpg\"><\/div>\n<p>Essa \u00e9 a primeira alta na proje\u00e7\u00e3o do PIB feita pelo mercado financeiro depois de 19 quedas consecutivas. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>Depois de 19 quedas seguidas, a proje\u00e7\u00e3o de institui\u00e7\u00f5es financeiras para o crescimento da economia, desta vez, foi levemente ajustada para cima. A estimativa para a expans\u00e3o do Produto Interno Bruto (PIB), soma de todos os bens e servi\u00e7os produzidos no pa\u00eds, subiu de 0,24% para 0,28%. Para 2015, permanece a estimativa de crescimento de 1%. Essas proje\u00e7\u00f5es fazem parte da pesquisa semanal do BC a institui\u00e7\u00f5es financeiras, sobre os principais indicadores econ\u00f4micos.<\/p>\n<p>A estimativa para a retra\u00e7\u00e3o da produ\u00e7\u00e3o industrial passou de 2,14% para 2,16%, em 2014. No pr\u00f3ximo ano, deve haver recupera\u00e7\u00e3o do setor, com crescimento de 1,3%, ante a previs\u00e3o da semana passada de 1,4%. A proje\u00e7\u00e3o para a cota\u00e7\u00e3o do d\u00f3lar permanece em R$ 2,40, este ano, e em R$ 2,50, em 2015.<\/p>\n<p>Para o \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA), a estimativa do mercado financeiro passou de 6,32% para 6,45%, este ano. Para 2015, segue em 6,3%. A proje\u00e7\u00e3o para a infla\u00e7\u00e3o ainda est\u00e1 longe do centro da meta (4,5%) e um pouco abaixo do limite superior (6,5%).<\/p>\n<p>A taxa b\u00e1sica de juros, a Selic \u2013 usada pelo BC para influenciar a economia e consequentemente, a infla\u00e7\u00e3o \u2013 deve fechar 2014 sem altera\u00e7\u00f5es, de acordo com as expectativas das institui\u00e7\u00f5es financeiras. Atualmente a Selic est\u00e1 em 11% ao ano. Mas em 2015, as institui\u00e7\u00f5es financeiras esperam por eleva\u00e7\u00e3o da taxa, que deve encerrar o per\u00edodo em 11,88% ao ano.<\/p>\n<p>Na pesquisa do BC tamb\u00e9m consta a estimativa para o \u00cdndice de Pre\u00e7os ao Consumidor (IPC) da Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (Fipe), segue em 5,38%, este ano, e em 5,59%, em 2015. Para IGP-M, a estimativa foi ajustada de 3,49% para 3,17%, este ano, e permanece em 5,5%, em 2015. A proje\u00e7\u00e3o para o \u00cdndice Geral de Pre\u00e7os-Disponibilidade Interna (IGP-DI) caiu de 3,63% para 3,19 em 2014, e subiu de 5,5% para 5,52%, em 2015. <strong>(Ag\u00eancia Brasil)<\/strong><\/p>\n<p>The post Mercado prev\u00ea que PIB do Brasil deve crescer 0,28% appeared first on Economia SC.<\/p>\n<p>Via: <a href=\"http:\/\/economiasc.com.br\/mercado-preve-que-pib-brasil-deve-crescer-028\/\" class=\"colorbox\" title=\"Mercado prev\u00ea que PIB do Brasil deve crescer 0,28%\">economiasc.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"ftpimagefix\" style=\"float:left\"><img decoding=\"async\" width=\"250\" alt=\"Essa \u00e9 a primeira alta na proje\u00e7\u00e3o do PIB feita pelo mercado financeiro depois de 19 quedas consecutivas. Foto: Divulga\u00e7\u00e3o\" src=\"http:\/\/economiasc.com.br\/wp-content\/uploads\/2014\/10\/indice-subind-300x200.jpg\"><\/div>\n<p>Essa \u00e9 a primeira alta na proje\u00e7\u00e3o do PIB feita pelo mercado financeiro depois de 19 quedas consecutivas. Foto: Divulga\u00e7\u00e3o<\/p>\n<p>Depois de 19 quedas seguidas, a proje\u00e7\u00e3o de institui\u00e7\u00f5es financeiras para o crescimento da economia, desta vez, foi levemente ajustada para cima. A estimativa para a expans\u00e3o do Produto Interno Bruto (PIB), soma de todos os bens e servi\u00e7os produzidos no pa\u00eds, subiu de 0,24% para 0,28%. Para 2015, permanece a estimativa de crescimento de 1%. Essas proje\u00e7\u00f5es fazem parte da pesquisa semanal do BC a institui\u00e7\u00f5es financeiras, sobre os principais indicadores econ\u00f4micos.<\/p>\n<p>A estimativa para a retra\u00e7\u00e3o da produ\u00e7\u00e3o industrial passou de 2,14% para 2,16%, em 2014. No pr\u00f3ximo ano, deve haver recupera\u00e7\u00e3o do setor, com crescimento de 1,3%, ante a previs\u00e3o da semana passada de 1,4%. A proje\u00e7\u00e3o para a cota\u00e7\u00e3o do d\u00f3lar permanece em R$ 2,40, este ano, e em R$ 2,50, em 2015.<\/p>\n<p>Para o \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA), a estimativa do mercado financeiro passou de 6,32% para 6,45%, este ano. Para 2015, segue em 6,3%. A proje\u00e7\u00e3o para a infla\u00e7\u00e3o ainda est\u00e1 longe do centro da meta (4,5%) e um pouco abaixo do limite superior (6,5%).<\/p>\n<p>A taxa b\u00e1sica de juros, a Selic \u2013 usada pelo BC para influenciar a economia e consequentemente, a infla\u00e7\u00e3o \u2013 deve fechar 2014 sem altera\u00e7\u00f5es, de acordo com as expectativas das institui\u00e7\u00f5es financeiras. Atualmente a Selic est\u00e1 em 11% ao ano. Mas em 2015, as institui\u00e7\u00f5es financeiras esperam por eleva\u00e7\u00e3o da taxa, que deve encerrar o per\u00edodo em 11,88% ao ano.<\/p>\n<p>Na pesquisa do BC tamb\u00e9m consta a estimativa para o \u00cdndice de Pre\u00e7os ao Consumidor (IPC) da Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (Fipe), segue em 5,38%, este ano, e em 5,59%, em 2015. Para IGP-M, a estimativa foi ajustada de 3,49% para 3,17%, este ano, e permanece em 5,5%, em 2015. A proje\u00e7\u00e3o para o \u00cdndice Geral de Pre\u00e7os-Disponibilidade Interna (IGP-DI) caiu de 3,63% para 3,19 em 2014, e subiu de 5,5% para 5,52%, em 2015. <strong>(Ag\u00eancia Brasil)<\/strong><\/p>\n<p>The post Mercado prev\u00ea que PIB do Brasil deve crescer 0,28% appeared first on Economia SC.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4261","post","type-post","status-publish","format-standard","hentry","category-noticias","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/comments?post=4261"}],"version-history":[{"count":0,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/posts\/4261\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/media?parent=4261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/categories?post=4261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdlbc.com.br\/portal\/wp-json\/wp\/v2\/tags?post=4261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}